{"id":1897,"date":"2011-07-14T08:50:00","date_gmt":"2011-07-14T08:50:00","guid":{"rendered":""},"modified":"2022-08-08T09:36:51","modified_gmt":"2022-08-08T09:36:51","slug":"aportacion-de-solar-cambio-de-obra","status":"publish","type":"post","link":"https:\/\/prayde.com\/empresa\/aportacion-de-solar-cambio-de-obra\/","title":{"rendered":"Aportaci\u00f3n de Solar a cambio de obra futura"},"content":{"rendered":"<p>Una modalidad de negocio en el que est\u00e1n interesados algunos due\u00f1os de solares, consiste, precisamente, en entregar el solar al promotor, a cambio de que este se obligue a entregar una parte determinada de la obra terminada, que va a construir sobre el propio solar, y no est\u00e1n interesados en otro tipo de permuta.<\/p>\n<p>Surge as\u00ed, un modelo de negocio que esta siendo aplicado con \u00e9xito por los promotores, en base a conciliar intereses contrapuestos, como son:<\/p>\n<p>Por parte del due\u00f1o del solar (CEDENTE)<br \/>\u00b7 Razones de desconocimiento profesional de gestionar una promoci\u00f3n inmobiliaria de cierta envergadura.<br \/>\u00b7 Intereses comerciales circunscritos al municipio y zona de ubicaci\u00f3n del solar (por ejemplo si es un comerciante con negocio abierto en la localidad que tiene la intenci\u00f3n de trasladarse a una nueva zona, donde radica el solar, situado en mejor zona comercial que el actual)<br \/>\u00b7 Intereses familiares (donar a sus hijos pisos en el mismo municipio<br \/>\u00b7 Intereses econ\u00f3micos, en coyunturas favorables, de evoluci\u00f3n al alza de los precios de viviendas y locales terminados, con lo que la operaci\u00f3n podr\u00eda suponer para el due\u00f1o del solar no renunciar a las posibles plusval\u00edas de estos productos a lo largo del tiempo, frente a la venta, en la que quedar\u00eda ajeno a la percepci\u00f3n de estas futuras plusval\u00edas.<br \/>\u00b7 Dificultades coyunturales, de encontrar comprador que pague en dinero<\/p>\n<p>Por parte del promotor (CESIONARIO):<br \/>\u00b7 Evitar el fuerte desembolso inicial que supone la adquisici\u00f3n del solar<br \/>\u00b7 Disminuir el volumen de cr\u00e9dito necesario para financiar la operaci\u00f3n.<br \/>\u00b7 Disminuir los gastos financieros<br \/>\u00b7 Dificultades coyunturales, de encontrar financiaci\u00f3n para la adquisici\u00f3n del solar con pago en dinero.<br \/>\u00b7 Disminuci\u00f3n del riesgo de venta, en situaciones coyunturales desfavorables, al suponer la operaci\u00f3n unas adjudicaciones iniciales el solar.<\/p>\n<p>Algunas de estas razones expuestas son controvertidas, incluso pueden ser valoradas de forma favorable o desfavorable, seg\u00fan sea la coyuntura econ\u00f3mica por la que atraviesa el sector inmobiliario, pero no cabe duda de que siempre tendr\u00edan elementos concretos dignos de un an\u00e1lisis profundo.<\/p>\n<p>Si bien el modelo propuesto satisface a los promotores, es evidente intuir el desequilibrio contractual existente en cada parte contratante:<\/p>\n<p>&#8211; El due\u00f1o del solar, entrega el bien, que queda en poder del promotor, que para que pueda ser viable la operaci\u00f3n, necesita de su plena disposici\u00f3n, ya que de otro modo, si existiera alguna cla\u00fasula resolutoria, suspensiva, etc., no lo podr\u00eda hipotecar, y en consecuencia la promoci\u00f3n se har\u00eda inviable, salvo que fuera realizada con fondos propios del promotor.<\/p>\n<p>&#8211; Frente a esta entrega real del bien, que el due\u00f1o del solar realiza, el promotor solo tiene una obligaci\u00f3n de futuro, la de entregar una parte de la obra, generalmente se estipula un plazo, que todav\u00eda debe realizar, que no existe en el momento de formalizar el acuerdo con el due\u00f1o, y que para su realizaci\u00f3n el promotor hipoteca solar y lo construido sobre el mismo a un tercero (contratista), y comercializa en plano, oblig\u00e1ndose con unos terceros a entregar el resto de la obra.<\/p>\n<p>Evidentemente, dicho desequilibrio se puede, y as\u00ed se ha llevado a efecto en muchas ocasiones por la confianza del duelo del solar con el promotor.<\/p>\n<p>Y el problema, desde el punto de vista jur\u00eddico se recrudece, ya que si acudimos a nuestro C\u00f3digo Civil, en busca de apoyo, nos encontramos con que dicho contrato no existe, y por tanto se trata de un contrato at\u00edpico, que la jurisprudencia ha tenido que lidiar en su interpretaci\u00f3n, y al que muchos autores jur\u00eddicos le han dedicado multitud de magn\u00edficos libros, de los que seleccionamos, algunos de ellos:<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una modalidad de negocio en el que est\u00e1n interesados algunos due\u00f1os de solares, consiste, precisamente, en entregar el solar al promotor, a cambio de que este se obligue a entregar\u2026 <a class=\"continue-reading-link\" href=\"https:\/\/prayde.com\/empresa\/aportacion-de-solar-cambio-de-obra\/\">Continue leyendo<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[32,19,29],"class_list":["post-1897","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-contratos","tag-legislacion","tag-suelo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aportaci\u00f3n de Solar a cambio de obra futura - Gestinmo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prayde.com\/empresa\/aportacion-de-solar-cambio-de-obra\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aportaci\u00f3n de Solar a cambio de obra futura - Gestinmo\" \/>\n<meta property=\"og:description\" content=\"Una modalidad de negocio en el que est\u00e1n interesados algunos due\u00f1os de solares, consiste, precisamente, en entregar el solar al promotor, a cambio de que este se obligue a entregar\u2026 Continue leyendo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prayde.com\/empresa\/aportacion-de-solar-cambio-de-obra\/\" \/>\n<meta property=\"og:site_name\" content=\"Gestinmo\" \/>\n<meta property=\"article:published_time\" content=\"2011-07-14T08:50:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-08T09:36:51+00:00\" \/>\n<meta name=\"author\" content=\"Juan Fernandez Caparros\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juan Fernandez Caparros\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/aportacion-de-solar-cambio-de-obra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/aportacion-de-solar-cambio-de-obra\\\/\"},\"author\":{\"name\":\"Juan Fernandez Caparros\",\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/#\\\/schema\\\/person\\\/ef6008d6bbfeae510b73653264512798\"},\"headline\":\"Aportaci\u00f3n de Solar a cambio de obra futura\",\"datePublished\":\"2011-07-14T08:50:00+00:00\",\"dateModified\":\"2022-08-08T09:36:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/aportacion-de-solar-cambio-de-obra\\\/\"},\"wordCount\":641,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/#organization\"},\"keywords\":[\"CONTRATOS\",\"legislacion\",\"Suelo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prayde.com\\\/empresa\\\/aportacion-de-solar-cambio-de-obra\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/aportacion-de-solar-cambio-de-obra\\\/\",\"url\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/aportacion-de-solar-cambio-de-obra\\\/\",\"name\":\"Aportaci\u00f3n de Solar a cambio de obra futura - Gestinmo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/#website\"},\"datePublished\":\"2011-07-14T08:50:00+00:00\",\"dateModified\":\"2022-08-08T09:36:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/aportacion-de-solar-cambio-de-obra\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prayde.com\\\/empresa\\\/aportacion-de-solar-cambio-de-obra\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/aportacion-de-solar-cambio-de-obra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aportaci\u00f3n de Solar a cambio de obra futura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/#website\",\"url\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/\",\"name\":\"Gestinmo\",\"description\":\"Analizar la Rentabilidad y Riesgos de una Promocion Inmobiliaria\",\"publisher\":{\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/#organization\",\"name\":\"Gestinmo\",\"url\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/cropped-cropped-Prayde-Pe.jpg\",\"contentUrl\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/cropped-cropped-Prayde-Pe.jpg\",\"width\":512,\"height\":512,\"caption\":\"Gestinmo\"},\"image\":{\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/#\\\/schema\\\/person\\\/ef6008d6bbfeae510b73653264512798\",\"name\":\"Juan Fernandez Caparros\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"Juan Fernandez Caparros\"},\"url\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/author\\\/06357885663078594681\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aportaci\u00f3n de Solar a cambio de obra futura - Gestinmo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prayde.com\/empresa\/aportacion-de-solar-cambio-de-obra\/","og_locale":"es_ES","og_type":"article","og_title":"Aportaci\u00f3n de Solar a cambio de obra futura - Gestinmo","og_description":"Una modalidad de negocio en el que est\u00e1n interesados algunos due\u00f1os de solares, consiste, precisamente, en entregar el solar al promotor, a cambio de que este se obligue a entregar\u2026 Continue leyendo","og_url":"https:\/\/prayde.com\/empresa\/aportacion-de-solar-cambio-de-obra\/","og_site_name":"Gestinmo","article_published_time":"2011-07-14T08:50:00+00:00","article_modified_time":"2022-08-08T09:36:51+00:00","author":"Juan Fernandez Caparros","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Juan Fernandez Caparros","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prayde.com\/empresa\/aportacion-de-solar-cambio-de-obra\/#article","isPartOf":{"@id":"https:\/\/prayde.com\/empresa\/aportacion-de-solar-cambio-de-obra\/"},"author":{"name":"Juan Fernandez Caparros","@id":"https:\/\/prayde.com\/empresa\/#\/schema\/person\/ef6008d6bbfeae510b73653264512798"},"headline":"Aportaci\u00f3n de Solar a cambio de obra futura","datePublished":"2011-07-14T08:50:00+00:00","dateModified":"2022-08-08T09:36:51+00:00","mainEntityOfPage":{"@id":"https:\/\/prayde.com\/empresa\/aportacion-de-solar-cambio-de-obra\/"},"wordCount":641,"commentCount":0,"publisher":{"@id":"https:\/\/prayde.com\/empresa\/#organization"},"keywords":["CONTRATOS","legislacion","Suelo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prayde.com\/empresa\/aportacion-de-solar-cambio-de-obra\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prayde.com\/empresa\/aportacion-de-solar-cambio-de-obra\/","url":"https:\/\/prayde.com\/empresa\/aportacion-de-solar-cambio-de-obra\/","name":"Aportaci\u00f3n de Solar a cambio de obra futura - Gestinmo","isPartOf":{"@id":"https:\/\/prayde.com\/empresa\/#website"},"datePublished":"2011-07-14T08:50:00+00:00","dateModified":"2022-08-08T09:36:51+00:00","breadcrumb":{"@id":"https:\/\/prayde.com\/empresa\/aportacion-de-solar-cambio-de-obra\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prayde.com\/empresa\/aportacion-de-solar-cambio-de-obra\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/prayde.com\/empresa\/aportacion-de-solar-cambio-de-obra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/prayde.com\/empresa\/"},{"@type":"ListItem","position":2,"name":"Aportaci\u00f3n de Solar a cambio de obra futura"}]},{"@type":"WebSite","@id":"https:\/\/prayde.com\/empresa\/#website","url":"https:\/\/prayde.com\/empresa\/","name":"Gestinmo","description":"Analizar la Rentabilidad y Riesgos de una Promocion Inmobiliaria","publisher":{"@id":"https:\/\/prayde.com\/empresa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prayde.com\/empresa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/prayde.com\/empresa\/#organization","name":"Gestinmo","url":"https:\/\/prayde.com\/empresa\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/prayde.com\/empresa\/#\/schema\/logo\/image\/","url":"https:\/\/prayde.com\/empresa\/wp-content\/uploads\/2018\/12\/cropped-cropped-Prayde-Pe.jpg","contentUrl":"https:\/\/prayde.com\/empresa\/wp-content\/uploads\/2018\/12\/cropped-cropped-Prayde-Pe.jpg","width":512,"height":512,"caption":"Gestinmo"},"image":{"@id":"https:\/\/prayde.com\/empresa\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/prayde.com\/empresa\/#\/schema\/person\/ef6008d6bbfeae510b73653264512798","name":"Juan Fernandez Caparros","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"Juan Fernandez Caparros"},"url":"https:\/\/prayde.com\/empresa\/author\/06357885663078594681\/"}]}},"_links":{"self":[{"href":"https:\/\/prayde.com\/empresa\/wp-json\/wp\/v2\/posts\/1897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prayde.com\/empresa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prayde.com\/empresa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prayde.com\/empresa\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/prayde.com\/empresa\/wp-json\/wp\/v2\/comments?post=1897"}],"version-history":[{"count":0,"href":"https:\/\/prayde.com\/empresa\/wp-json\/wp\/v2\/posts\/1897\/revisions"}],"wp:attachment":[{"href":"https:\/\/prayde.com\/empresa\/wp-json\/wp\/v2\/media?parent=1897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prayde.com\/empresa\/wp-json\/wp\/v2\/categories?post=1897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prayde.com\/empresa\/wp-json\/wp\/v2\/tags?post=1897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}