{"id":1864,"date":"2012-02-03T09:28:00","date_gmt":"2012-02-03T09:28:00","guid":{"rendered":""},"modified":"2022-08-08T09:36:28","modified_gmt":"2022-08-08T09:36:28","slug":"reglamento-de-valoraciones-de-la-ley-4","status":"publish","type":"post","link":"https:\/\/prayde.com\/empresa\/reglamento-de-valoraciones-de-la-ley-4\/","title":{"rendered":"Reglamento de Valoraciones de la Ley del Suelo: Ejemplo Valoraci\u00f3n Suelo Rustico"},"content":{"rendered":"<div style=\"font-family: Arial,Helvetica,sans-serif;\">\nEl pasado d\u00eda 10 de noviembre de 2011 entro en vigor el nuevo <a href=\"http:\/\/www.boe.es\/boe\/dias\/2011\/11\/09\/pdfs\/BOE-A-2011-17629.pdf\">Reglamento de Valoraciones de la Ley del Suelo<\/a> aprobado por el RD 1492\/2011, de 24 de octubre.<\/p>\n<p>En esta publicaci\u00f3n se pretende <b>aplicar el m\u00e9todo de valoraci\u00f3n propuesto en el citado Reglamento a un suelo<\/b> de 1.000.000 m2&nbsp; que se consideren situaci\u00f3n b\u00e1sica de <b>suelo rural, a que no tiene explotaci\u00f3n alguna<\/b> pero que se encuentra cerca de n\u00facleos relativamente poblados y centros de actividad de cierta importancia.<\/div>\n<div style=\"font-family: Arial,Helvetica,sans-serif;\">\n<\/div>\n<div style=\"font-family: Arial,Helvetica,sans-serif;\">\n<br \/><b>ENUNCIADO<\/b>.- Se trata de aplicar la valoraci\u00f3n de los terrenos de 1.000.000 m2, al caso de suelo rural de imposible explotaci\u00f3n. <\/p>\n<p>Se ha informado por estudios estad\u00edsticos de la zona publicados por la Comunidad Aut\u00f3noma, que la <b>renta m\u00ednima de la Tierra es de 2.000 Euros.\/ha y a\u00f1o<\/b>, y que los habitantes de los n\u00facleos de poblaci\u00f3n situados a menos de 4 Km. de dichos terrenos ascienden a 100.000 habitantes y que los habitantes de otro n\u00facleo de poblaci\u00f3n situados a mas de 4 Km. y menos de 40 Km. tienen un total de 60.000 habitantes.<\/p>\n<p>Tambi\u00e9n es consciente de que&nbsp;<b> a 5 Km. de los terrenos esta situado un gran complejo urbanizado de uso terciario<\/b>, y que no existen en su entorno zonas de singular valor ambiental o paisaj\u00edstico.<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211; SOLUCION &#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n<p>Aplicamos las formulas de los art\u00edculos 16 y 17 del Reglamento de valoraciones de la Ley del Suelo:<\/p>\n<p>VS = U1 x U2 x U3 x (1\/3 Renta M\u00ednima Tierra)\/i<\/p>\n<p>U1 = factor de accesibilidad a n\u00facleos de poblaci\u00f3n = 1 + (100.000 + 60.000\/3)\/1.000.000 = 1,12<\/p>\n<p>U2 = factor de accesibilidad a centros de actividad econ\u00f3mica = 1,6 \u2013 0,01 x 5 = 1,55<\/p>\n<p>U3 = factor de ubicaci\u00f3n en entornos de singular valor ambiental o paisaj\u00edstico = 1,00 (no hay)<\/p>\n<p>Comprobamos la limitaci\u00f3n del factor de localizaci\u00f3n global = F1 = U1 x U2 x U3 (&lt; 2,00) = 1,12 x 1,55 x 1,00 = 1,736 <\/p>\n<p>Tipo de capitalizaci\u00f3n = Rendimiento Interno Deuda Publica a plazo de entre 2 y 6 a\u00f1os, ultima referencia publicada por el Banco de Espa\u00f1a, correspondiente al mes de diciembre de 2011, que es: 4,459%<\/p>\n<p>Luego el<b> valor del suelo rural de imposible explotaci\u00f3n<\/b> ser\u00e1:<\/p>\n<p>VS = 1,73 x (100 x 1\/3 (2.000))\/0,04459 = <b>2.586.529 euros<\/b><\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;- X &#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n<p>NOTA:<br \/>Se ha estimado, a efectos de la soluci\u00f3n de este caso, como renta m\u00ednima de la tierra, un valor que no tiene base estad\u00edstica alguna, al desconocerse dicho dato<\/p>\n<p><b>El art. 16 del Reglamento citado define la renta m\u00ednima de la tierra a partir de estudios estad\u00edsticos, de los cuales, al d\u00eda de hoy, no tenemos conocimiento de que existan,<\/b> siendo este un dato fundamental e imprescindible en la valoraci\u00f3n <\/p>\n<p>Si alg\u00fan lector conoce esas fuentes estad\u00edsticas, rogamos lo comente para el general conocimiento de los interesados.<br \/>&nbsp;<\/div>\n<div style=\"font-family: Arial,Helvetica,sans-serif;\">\n<\/div>\n<p><br style=\"font-family: Arial,Helvetica,sans-serif;\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado d\u00eda 10 de noviembre de 2011 entro en vigor el nuevo Reglamento de Valoraciones de la Ley del Suelo aprobado por el RD 1492\/2011, de 24 de octubre.\u2026 <a class=\"continue-reading-link\" href=\"https:\/\/prayde.com\/empresa\/reglamento-de-valoraciones-de-la-ley-4\/\">Continue leyendo<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[19,33,29],"class_list":["post-1864","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-legislacion","tag-opinion","tag-suelo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reglamento de Valoraciones de la Ley del Suelo: Ejemplo Valoraci\u00f3n Suelo Rustico - Gestinmo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prayde.com\/empresa\/reglamento-de-valoraciones-de-la-ley-4\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reglamento de Valoraciones de la Ley del Suelo: Ejemplo Valoraci\u00f3n Suelo Rustico - Gestinmo\" \/>\n<meta property=\"og:description\" content=\"El pasado d\u00eda 10 de noviembre de 2011 entro en vigor el nuevo Reglamento de Valoraciones de la Ley del Suelo aprobado por el RD 1492\/2011, de 24 de octubre.\u2026 Continue leyendo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prayde.com\/empresa\/reglamento-de-valoraciones-de-la-ley-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Gestinmo\" \/>\n<meta property=\"article:published_time\" content=\"2012-02-03T09:28:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-08T09:36:28+00:00\" \/>\n<meta name=\"author\" content=\"Juan Fernandez Caparros\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juan Fernandez Caparros\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/reglamento-de-valoraciones-de-la-ley-4\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/reglamento-de-valoraciones-de-la-ley-4\\\/\"},\"author\":{\"name\":\"Juan Fernandez Caparros\",\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/#\\\/schema\\\/person\\\/ef6008d6bbfeae510b73653264512798\"},\"headline\":\"Reglamento de Valoraciones de la Ley del Suelo: Ejemplo Valoraci\u00f3n Suelo Rustico\",\"datePublished\":\"2012-02-03T09:28:00+00:00\",\"dateModified\":\"2022-08-08T09:36:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/reglamento-de-valoraciones-de-la-ley-4\\\/\"},\"wordCount\":470,\"commentCount\":6,\"publisher\":{\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/#organization\"},\"keywords\":[\"legislacion\",\"Opinion\",\"Suelo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prayde.com\\\/empresa\\\/reglamento-de-valoraciones-de-la-ley-4\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/reglamento-de-valoraciones-de-la-ley-4\\\/\",\"url\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/reglamento-de-valoraciones-de-la-ley-4\\\/\",\"name\":\"Reglamento de Valoraciones de la Ley del Suelo: Ejemplo Valoraci\u00f3n Suelo Rustico - Gestinmo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/#website\"},\"datePublished\":\"2012-02-03T09:28:00+00:00\",\"dateModified\":\"2022-08-08T09:36:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/reglamento-de-valoraciones-de-la-ley-4\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prayde.com\\\/empresa\\\/reglamento-de-valoraciones-de-la-ley-4\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/reglamento-de-valoraciones-de-la-ley-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reglamento de Valoraciones de la Ley del Suelo: Ejemplo Valoraci\u00f3n Suelo Rustico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/#website\",\"url\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/\",\"name\":\"Gestinmo\",\"description\":\"Analizar la Rentabilidad y Riesgos de una Promocion Inmobiliaria\",\"publisher\":{\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/#organization\",\"name\":\"Gestinmo\",\"url\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/cropped-cropped-Prayde-Pe.jpg\",\"contentUrl\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/cropped-cropped-Prayde-Pe.jpg\",\"width\":512,\"height\":512,\"caption\":\"Gestinmo\"},\"image\":{\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/#\\\/schema\\\/person\\\/ef6008d6bbfeae510b73653264512798\",\"name\":\"Juan Fernandez Caparros\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"Juan Fernandez Caparros\"},\"url\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/author\\\/06357885663078594681\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reglamento de Valoraciones de la Ley del Suelo: Ejemplo Valoraci\u00f3n Suelo Rustico - Gestinmo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prayde.com\/empresa\/reglamento-de-valoraciones-de-la-ley-4\/","og_locale":"es_ES","og_type":"article","og_title":"Reglamento de Valoraciones de la Ley del Suelo: Ejemplo Valoraci\u00f3n Suelo Rustico - Gestinmo","og_description":"El pasado d\u00eda 10 de noviembre de 2011 entro en vigor el nuevo Reglamento de Valoraciones de la Ley del Suelo aprobado por el RD 1492\/2011, de 24 de octubre.\u2026 Continue leyendo","og_url":"https:\/\/prayde.com\/empresa\/reglamento-de-valoraciones-de-la-ley-4\/","og_site_name":"Gestinmo","article_published_time":"2012-02-03T09:28:00+00:00","article_modified_time":"2022-08-08T09:36:28+00:00","author":"Juan Fernandez Caparros","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Juan Fernandez Caparros","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prayde.com\/empresa\/reglamento-de-valoraciones-de-la-ley-4\/#article","isPartOf":{"@id":"https:\/\/prayde.com\/empresa\/reglamento-de-valoraciones-de-la-ley-4\/"},"author":{"name":"Juan Fernandez Caparros","@id":"https:\/\/prayde.com\/empresa\/#\/schema\/person\/ef6008d6bbfeae510b73653264512798"},"headline":"Reglamento de Valoraciones de la Ley del Suelo: Ejemplo Valoraci\u00f3n Suelo Rustico","datePublished":"2012-02-03T09:28:00+00:00","dateModified":"2022-08-08T09:36:28+00:00","mainEntityOfPage":{"@id":"https:\/\/prayde.com\/empresa\/reglamento-de-valoraciones-de-la-ley-4\/"},"wordCount":470,"commentCount":6,"publisher":{"@id":"https:\/\/prayde.com\/empresa\/#organization"},"keywords":["legislacion","Opinion","Suelo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prayde.com\/empresa\/reglamento-de-valoraciones-de-la-ley-4\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prayde.com\/empresa\/reglamento-de-valoraciones-de-la-ley-4\/","url":"https:\/\/prayde.com\/empresa\/reglamento-de-valoraciones-de-la-ley-4\/","name":"Reglamento de Valoraciones de la Ley del Suelo: Ejemplo Valoraci\u00f3n Suelo Rustico - Gestinmo","isPartOf":{"@id":"https:\/\/prayde.com\/empresa\/#website"},"datePublished":"2012-02-03T09:28:00+00:00","dateModified":"2022-08-08T09:36:28+00:00","breadcrumb":{"@id":"https:\/\/prayde.com\/empresa\/reglamento-de-valoraciones-de-la-ley-4\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prayde.com\/empresa\/reglamento-de-valoraciones-de-la-ley-4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/prayde.com\/empresa\/reglamento-de-valoraciones-de-la-ley-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/prayde.com\/empresa\/"},{"@type":"ListItem","position":2,"name":"Reglamento de Valoraciones de la Ley del Suelo: Ejemplo Valoraci\u00f3n Suelo Rustico"}]},{"@type":"WebSite","@id":"https:\/\/prayde.com\/empresa\/#website","url":"https:\/\/prayde.com\/empresa\/","name":"Gestinmo","description":"Analizar la Rentabilidad y Riesgos de una Promocion Inmobiliaria","publisher":{"@id":"https:\/\/prayde.com\/empresa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prayde.com\/empresa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/prayde.com\/empresa\/#organization","name":"Gestinmo","url":"https:\/\/prayde.com\/empresa\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/prayde.com\/empresa\/#\/schema\/logo\/image\/","url":"https:\/\/prayde.com\/empresa\/wp-content\/uploads\/2018\/12\/cropped-cropped-Prayde-Pe.jpg","contentUrl":"https:\/\/prayde.com\/empresa\/wp-content\/uploads\/2018\/12\/cropped-cropped-Prayde-Pe.jpg","width":512,"height":512,"caption":"Gestinmo"},"image":{"@id":"https:\/\/prayde.com\/empresa\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/prayde.com\/empresa\/#\/schema\/person\/ef6008d6bbfeae510b73653264512798","name":"Juan Fernandez Caparros","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"Juan Fernandez Caparros"},"url":"https:\/\/prayde.com\/empresa\/author\/06357885663078594681\/"}]}},"_links":{"self":[{"href":"https:\/\/prayde.com\/empresa\/wp-json\/wp\/v2\/posts\/1864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prayde.com\/empresa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prayde.com\/empresa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prayde.com\/empresa\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/prayde.com\/empresa\/wp-json\/wp\/v2\/comments?post=1864"}],"version-history":[{"count":0,"href":"https:\/\/prayde.com\/empresa\/wp-json\/wp\/v2\/posts\/1864\/revisions"}],"wp:attachment":[{"href":"https:\/\/prayde.com\/empresa\/wp-json\/wp\/v2\/media?parent=1864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prayde.com\/empresa\/wp-json\/wp\/v2\/categories?post=1864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prayde.com\/empresa\/wp-json\/wp\/v2\/tags?post=1864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}