{"id":1834,"date":"2012-09-06T09:28:00","date_gmt":"2012-09-06T09:28:00","guid":{"rendered":""},"modified":"2022-08-08T09:36:10","modified_gmt":"2022-08-08T09:36:10","slug":"analisis-de-sensibilidad-variables","status":"publish","type":"post","link":"https:\/\/prayde.com\/empresa\/analisis-de-sensibilidad-variables\/","title":{"rendered":"An\u00e1lisis de Sensibilidad. Variables Estrat\u00e9gicas frente a Alternativas de Viabilidad"},"content":{"rendered":"<p><!--[if gte mso 9]><xml>\n <o:OfficeDocumentSettings>\n  <o:TargetScreenSize>800x600<\/o:TargetScreenSize>\n <\/o:OfficeDocumentSettings>\n<\/xml><![endif]--><br \/>\n<!--[if gte mso 9]><xml>\n <w:WordDocument>\n  <w:View>Normal<\/w:View>\n  <w:Zoom>0<\/w:Zoom>\n  <w:TrackMoves\/>\n  <w:TrackFormatting\/>\n  <w:HyphenationZone>21<\/w:HyphenationZone>\n  <w:PunctuationKerning\/>\n  <w:ValidateAgainstSchemas\/>\n  <w:SaveIfXMLInvalid>false<\/w:SaveIfXMLInvalid>\n  <w:IgnoreMixedContent>false<\/w:IgnoreMixedContent>\n  <w:AlwaysShowPlaceholderText>false<\/w:AlwaysShowPlaceholderText>\n  <w:DoNotPromoteQF\/>\n  <w:LidThemeOther>ES<\/w:LidThemeOther>\n  <w:LidThemeAsian>X-NONE<\/w:LidThemeAsian>\n  <w:LidThemeComplexScript>X-NONE<\/w:LidThemeComplexScript>\n  <w:Compatibility>\n   <w:BreakWrappedTables\/>\n   <w:SnapToGridInCell\/>\n   <w:WrapTextWithPunct\/>\n   <w:UseAsianBreakRules\/>\n   <w:DontGrowAutofit\/>\n   <w:SplitPgBreakAndParaMark\/>\n   <w:EnableOpenTypeKerning\/>\n   <w:DontFlipMirrorIndents\/>\n   <w:OverrideTableStyleHps\/>\n  <\/w:Compatibility>\n  <w:BrowserLevel>MicrosoftInternetExplorer4<\/w:BrowserLevel>\n  <m:mathPr>\n   <m:mathFont m:val=\"Cambria Math\"\/>\n   <m:brkBin m:val=\"before\"\/>\n   <m:brkBinSub m:val=\"&#45;-\"\/>\n   <m:smallFrac m:val=\"off\"\/>\n   <m:dispDef\/>\n   <m:lMargin m:val=\"0\"\/>\n   <m:rMargin m:val=\"0\"\/>\n   <m:defJc m:val=\"centerGroup\"\/>\n   <m:wrapIndent m:val=\"1440\"\/>\n   <m:intLim m:val=\"subSup\"\/>\n   <m:naryLim m:val=\"undOvr\"\/>\n  <\/m:mathPr><\/w:WordDocument>\n<\/xml><![endif]--><!--[if gte mso 9]><xml>\n <w:LatentStyles DefLockedState=\"false\" DefUnhideWhenUsed=\"true\"\n  DefSemiHidden=\"true\" DefQFormat=\"false\" DefPriority=\"99\"\n  LatentStyleCount=\"267\">\n  <w:LsdException Locked=\"false\" Priority=\"0\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Normal\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"9\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"heading 1\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 2\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 3\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 4\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 5\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 6\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 7\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 8\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 9\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 1\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 2\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 3\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 4\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 5\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 6\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 7\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 8\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 9\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"35\" QFormat=\"true\" Name=\"caption\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"10\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Title\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"0\" Name=\"Default Paragraph Font\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"11\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Subtitle\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"22\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Strong\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"20\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Emphasis\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"59\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Table Grid\"\/>\n  <w:LsdException Locked=\"false\" UnhideWhenUsed=\"false\" Name=\"Placeholder Text\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"1\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"No Spacing\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"60\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Light Shading\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"61\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Light List\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"62\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Light Grid\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"63\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Shading 1\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"64\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Shading 2\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"65\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium List 1\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"66\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium List 2\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"67\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Grid 1\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"68\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Grid 2\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"69\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Grid 3\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"70\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Dark List\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"71\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Colorful Shading\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"72\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Colorful List\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"73\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Colorful Grid\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"60\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Light Shading Accent 1\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"61\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Light List Accent 1\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"62\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Light Grid Accent 1\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"63\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Shading 1 Accent 1\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"64\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Shading 2 Accent 1\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"65\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium List 1 Accent 1\"\/>\n  <w:LsdException Locked=\"false\" UnhideWhenUsed=\"false\" Name=\"Revision\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"34\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"List Paragraph\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"29\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Quote\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"30\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Intense Quote\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"66\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium List 2 Accent 1\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"67\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Grid 1 Accent 1\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"68\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Grid 2 Accent 1\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"69\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Grid 3 Accent 1\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"70\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Dark List Accent 1\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"71\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Colorful Shading Accent 1\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"72\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Colorful List Accent 1\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"73\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Colorful Grid Accent 1\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"60\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Light Shading Accent 2\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"61\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Light List Accent 2\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"62\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Light Grid Accent 2\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"63\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Shading 1 Accent 2\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"64\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Shading 2 Accent 2\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"65\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium List 1 Accent 2\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"66\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium List 2 Accent 2\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"67\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Grid 1 Accent 2\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"68\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Grid 2 Accent 2\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"69\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Grid 3 Accent 2\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"70\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Dark List Accent 2\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"71\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Colorful Shading Accent 2\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"72\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Colorful List Accent 2\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"73\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Colorful Grid Accent 2\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"60\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Light Shading Accent 3\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"61\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Light List Accent 3\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"62\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Light Grid Accent 3\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"63\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Shading 1 Accent 3\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"64\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Shading 2 Accent 3\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"65\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium List 1 Accent 3\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"66\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium List 2 Accent 3\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"67\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Grid 1 Accent 3\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"68\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Grid 2 Accent 3\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"69\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Grid 3 Accent 3\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"70\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Dark List Accent 3\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"71\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Colorful Shading Accent 3\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"72\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Colorful List Accent 3\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"73\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Colorful Grid Accent 3\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"60\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Light Shading Accent 4\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"61\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Light List Accent 4\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"62\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Light Grid Accent 4\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"63\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Shading 1 Accent 4\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"64\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Shading 2 Accent 4\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"65\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium List 1 Accent 4\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"66\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium List 2 Accent 4\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"67\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Grid 1 Accent 4\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"68\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Grid 2 Accent 4\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"69\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Grid 3 Accent 4\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"70\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Dark List Accent 4\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"71\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Colorful Shading Accent 4\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"72\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Colorful List Accent 4\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"73\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Colorful Grid Accent 4\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"60\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Light Shading Accent 5\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"61\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Light List Accent 5\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"62\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Light Grid Accent 5\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"63\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Shading 1 Accent 5\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"64\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Shading 2 Accent 5\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"65\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium List 1 Accent 5\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"66\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium List 2 Accent 5\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"67\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Grid 1 Accent 5\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"68\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Grid 2 Accent 5\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"69\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Grid 3 Accent 5\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"70\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Dark List Accent 5\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"71\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Colorful Shading Accent 5\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"72\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Colorful List Accent 5\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"73\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Colorful Grid Accent 5\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"60\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Light Shading Accent 6\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"61\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Light List Accent 6\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"62\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Light Grid Accent 6\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"63\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Shading 1 Accent 6\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"64\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Shading 2 Accent 6\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"65\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium List 1 Accent 6\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"66\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium List 2 Accent 6\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"67\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Grid 1 Accent 6\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"68\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Grid 2 Accent 6\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"69\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Medium Grid 3 Accent 6\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"70\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Dark List Accent 6\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"71\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Colorful Shading Accent 6\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"72\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Colorful List Accent 6\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"73\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" Name=\"Colorful Grid Accent 6\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"19\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Subtle Emphasis\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"21\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Intense Emphasis\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"31\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Subtle Reference\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"32\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Intense Reference\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"33\" SemiHidden=\"false\"\n   UnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Book Title\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"37\" Name=\"Bibliography\"\/>\n  <w:LsdException Locked=\"false\" Priority=\"39\" QFormat=\"true\" Name=\"TOC Heading\"\/>\n <\/w:LatentStyles>\n<\/xml><![endif]--><!--[if gte mso 10]>\n\n\n<style>\n \/* Style Definitions *\/\n table.MsoNormalTable\n {mso-style-name:\"Tabla normal\";\n mso-tstyle-rowband-size:0;\n mso-tstyle-colband-size:0;\n mso-style-noshow:yes;\n mso-style-priority:99;\n mso-style-parent:\"\";\n mso-padding-alt:0cm 5.4pt 0cm 5.4pt;\n mso-para-margin:0cm;\n mso-para-margin-bottom:.0001pt;\n mso-pagination:widow-orphan;\n font-size:10.0pt;\n font-family:\"Times New Roman\",\"serif\";}\n<\/style>\n\n\n<![endif]--><\/p>\n<p><\/p>\n<div style=\"text-align: justify;\">\n<b style=\"mso-bidi-font-weight: normal;\"><span style=\"font-family: &quot;Arial&quot;,&quot;sans-serif&quot;; font-size: 11.0pt;\">El<br \/>\nestudio de viabilidad<\/span><\/b><span style=\"font-family: &quot;Arial&quot;,&quot;sans-serif&quot;; font-size: 11.0pt;\"><br \/>\necon\u00f3mica y financiera de una determinada promoci\u00f3n inmobiliaria, <b style=\"mso-bidi-font-weight: normal;\">requiere contemplar una serie de variables<br \/>\nque influyen en su desarrollo<\/b> y que tienen una consecuencia econ\u00f3mica en<br \/>\nlos costes de la promoci\u00f3n.<\/span><\/div>\n<div style=\"text-align: justify;\">\n<\/div>\n<div style=\"text-align: justify;\">\n<span style=\"font-family: &quot;Arial&quot;,&quot;sans-serif&quot;; font-size: 11.0pt;\">En consultas anteriores se ha se\u00f1alado el<br \/>\ncontenido del An\u00e1lisis de Sensibilidad y las fases de las que consta. En primer<br \/>\nlugar hay que elegir los par\u00e1metros de resultado que se desean analizar para, a<br \/>\ncontinuaci\u00f3n, estimar cuales son sus variables estrat\u00e9gicas.<\/span><\/div>\n<div style=\"text-align: justify;\">\n<\/div>\n<div style=\"text-align: justify;\">\n<span style=\"font-family: &quot;Arial&quot;,&quot;sans-serif&quot;; font-size: 11.0pt;\">Esta se determinan viendo como afectan a la<br \/>\nvariable resultado elegida, PEQUE\u00d1OS CAMBIOS de la variables estrat\u00e9gica.<\/span><\/div>\n<div style=\"text-align: justify;\">\n<\/div>\n<div style=\"text-align: justify;\">\n<span style=\"font-family: &quot;Arial&quot;,&quot;sans-serif&quot;; font-size: 11.0pt;\">Y, aqu\u00ed es importante se\u00f1alar, de que no solo<br \/>\nse trata de peque\u00f1os cambios, sino de cambios que NO ALTEREN LAS HIPOTESIS DE<br \/>\nPARTIDA Y SEAN SOBRE TODO IMPREDECIBLES INICIALMENTE, en el momento en el que<br \/>\nse platea el An\u00e1lisis de Viabilidad de la Promoci\u00f3n.<\/span><\/div>\n<div style=\"text-align: justify;\">\n<\/div>\n<div style=\"text-align: justify;\">\n<span style=\"font-family: &quot;Arial&quot;,&quot;sans-serif&quot;; font-size: 11.0pt;\">Es decir <b style=\"mso-bidi-font-weight: normal;\">hay<br \/>\nque distinguir claramente el significado de An\u00e1lisis de Viabilidad, donde se<br \/>\nplatean las alternativas a estudiar, y el An\u00e1lisis de Sensibilidad, que trata<br \/>\nde calcular los efectos que se producen por desv\u00edos no previstas en las<br \/>\nalternativas elegidas en el anterior an\u00e1lisis de viabilidad.<\/b><\/span><\/div>\n<div style=\"text-align: justify;\">\n<\/div>\n<div style=\"text-align: justify;\">\n<span style=\"font-family: &quot;Arial&quot;,&quot;sans-serif&quot;; font-size: 11.0pt;\">Es decir, el <b style=\"mso-bidi-font-weight: normal;\">an\u00e1lisis de Viabilidad no modifica las hip\u00f3tesis de partida<\/b>, solo pretende,<br \/>\nestudiar los efectos de cambios no previstos en aquellas.<\/span><\/div>\n<div style=\"text-align: justify;\">\n<\/div>\n<div style=\"text-align: justify;\">\n<span style=\"font-family: &quot;Arial&quot;,&quot;sans-serif&quot;; font-size: 11.0pt;\">Por ejemplo en el <b style=\"mso-bidi-font-weight: normal;\">An\u00e1lisis de Viabilidad podremos plantear diversas alternativas para realizar<br \/>\nuna promoci\u00f3n<\/b> inmobiliaria: en venta, en alquiler, en alquiler con opci\u00f3n<br \/>\nde compra, como Vivienda Libre, como Vivienda Protegida, etc. Todas ellas ser\u00e1n<br \/>\nalternativas. <\/span><\/div>\n<div style=\"text-align: justify;\">\n<\/div>\n<div style=\"text-align: justify;\">\n<span style=\"font-family: &quot;Arial&quot;,&quot;sans-serif&quot;; font-size: 11.0pt;\">Profundizando mas en cada proceso, si en una<br \/>\ndeterminada promoci\u00f3n, que se realiza en un conocido Ayuntamiento, planteamos,<br \/>\ncomo hip\u00f3tesis de partida que la <b style=\"mso-bidi-font-weight: normal;\">licencia<br \/>\nde obras<\/b> viene a tardar, seg\u00fan nuestra propia experiencia anterior, seis<br \/>\nmeses, esta ser\u00e1 la hip\u00f3tesis o alternativa de partida. <b style=\"mso-bidi-font-weight: normal;\">El an\u00e1lisis de sensibilidad efectuara peque\u00f1as variaciones en ese<br \/>\nplazo, pero no plantear\u00e1 un plazo de dos a\u00f1os, para la concesi\u00f3n de licencia, <\/b>porque<br \/>\nesto ser\u00e1 otra hip\u00f3tesis de partida.<\/span><\/div>\n<div style=\"text-align: justify;\">\n<\/div>\n<div style=\"text-align: justify;\">\n<span style=\"font-family: &quot;Arial&quot;,&quot;sans-serif&quot;; font-size: 11.0pt;\">Otro ejemplo grafico, lo tenemos en la <b style=\"mso-bidi-font-weight: normal;\">financiaci\u00f3n por pr\u00e9stamo hipotecario<\/b>.<br \/>\nSi, la hip\u00f3tesis de partida ser\u00e1 que no iban a conceder un pr\u00e9stamo del 70 %<br \/>\ndel precio de venta del cual \u00edbamos a disponer en un 80% durante la construcci\u00f3n,<br \/>\n<b style=\"mso-bidi-font-weight: normal;\">el an\u00e1lisis de sensibilidad partir\u00e1 de<br \/>\nesta hip\u00f3tesis<\/b> establecida en el estudio de viabilidad, y analizar peque\u00f1as<br \/>\ndesviaciones en el dichos porcentajes, <b style=\"mso-bidi-font-weight: normal;\">pero<br \/>\nno establecer\u00e1 una nueva hip\u00f3tesis de, por ejemplo, acometer la promoci\u00f3n exclusivamente<br \/>\ncon fondos propio<\/b>s, ya que esta ser\u00e1 una alternativa que pertenece siempre<br \/>\nal campo del An\u00e1lisis de Viabilidad.<\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El estudio de viabilidad econ\u00f3mica y financiera de una determinada promoci\u00f3n inmobiliaria, requiere contemplar una serie de variables que influyen en su desarrollo y que tienen una consecuencia econ\u00f3mica en\u2026 <a class=\"continue-reading-link\" href=\"https:\/\/prayde.com\/empresa\/analisis-de-sensibilidad-variables\/\">Continue leyendo<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[42,24,21],"class_list":["post-1834","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-analisis","tag-viabilidad","tag-vivienda"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>An\u00e1lisis de Sensibilidad. Variables Estrat\u00e9gicas frente a Alternativas de Viabilidad - Gestinmo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prayde.com\/empresa\/analisis-de-sensibilidad-variables\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"An\u00e1lisis de Sensibilidad. Variables Estrat\u00e9gicas frente a Alternativas de Viabilidad - Gestinmo\" \/>\n<meta property=\"og:description\" content=\"El estudio de viabilidad econ\u00f3mica y financiera de una determinada promoci\u00f3n inmobiliaria, requiere contemplar una serie de variables que influyen en su desarrollo y que tienen una consecuencia econ\u00f3mica en\u2026 Continue leyendo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prayde.com\/empresa\/analisis-de-sensibilidad-variables\/\" \/>\n<meta property=\"og:site_name\" content=\"Gestinmo\" \/>\n<meta property=\"article:published_time\" content=\"2012-09-06T09:28:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-08T09:36:10+00:00\" \/>\n<meta name=\"author\" content=\"Juan Fernandez Caparros\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juan Fernandez Caparros\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/analisis-de-sensibilidad-variables\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/analisis-de-sensibilidad-variables\\\/\"},\"author\":{\"name\":\"Juan Fernandez Caparros\",\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/#\\\/schema\\\/person\\\/ef6008d6bbfeae510b73653264512798\"},\"headline\":\"An\u00e1lisis de Sensibilidad. Variables Estrat\u00e9gicas frente a Alternativas de Viabilidad\",\"datePublished\":\"2012-09-06T09:28:00+00:00\",\"dateModified\":\"2022-08-08T09:36:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/analisis-de-sensibilidad-variables\\\/\"},\"wordCount\":470,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/#organization\"},\"keywords\":[\"analisis\",\"viabilidad\",\"vivienda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prayde.com\\\/empresa\\\/analisis-de-sensibilidad-variables\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/analisis-de-sensibilidad-variables\\\/\",\"url\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/analisis-de-sensibilidad-variables\\\/\",\"name\":\"An\u00e1lisis de Sensibilidad. Variables Estrat\u00e9gicas frente a Alternativas de Viabilidad - Gestinmo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/#website\"},\"datePublished\":\"2012-09-06T09:28:00+00:00\",\"dateModified\":\"2022-08-08T09:36:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/analisis-de-sensibilidad-variables\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prayde.com\\\/empresa\\\/analisis-de-sensibilidad-variables\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/analisis-de-sensibilidad-variables\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"An\u00e1lisis de Sensibilidad. Variables Estrat\u00e9gicas frente a Alternativas de Viabilidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/#website\",\"url\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/\",\"name\":\"Gestinmo\",\"description\":\"Analizar la Rentabilidad y Riesgos de una Promocion Inmobiliaria\",\"publisher\":{\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/#organization\",\"name\":\"Gestinmo\",\"url\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/cropped-cropped-Prayde-Pe.jpg\",\"contentUrl\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/cropped-cropped-Prayde-Pe.jpg\",\"width\":512,\"height\":512,\"caption\":\"Gestinmo\"},\"image\":{\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/#\\\/schema\\\/person\\\/ef6008d6bbfeae510b73653264512798\",\"name\":\"Juan Fernandez Caparros\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"Juan Fernandez Caparros\"},\"url\":\"https:\\\/\\\/prayde.com\\\/empresa\\\/author\\\/06357885663078594681\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"An\u00e1lisis de Sensibilidad. Variables Estrat\u00e9gicas frente a Alternativas de Viabilidad - Gestinmo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prayde.com\/empresa\/analisis-de-sensibilidad-variables\/","og_locale":"es_ES","og_type":"article","og_title":"An\u00e1lisis de Sensibilidad. Variables Estrat\u00e9gicas frente a Alternativas de Viabilidad - Gestinmo","og_description":"El estudio de viabilidad econ\u00f3mica y financiera de una determinada promoci\u00f3n inmobiliaria, requiere contemplar una serie de variables que influyen en su desarrollo y que tienen una consecuencia econ\u00f3mica en\u2026 Continue leyendo","og_url":"https:\/\/prayde.com\/empresa\/analisis-de-sensibilidad-variables\/","og_site_name":"Gestinmo","article_published_time":"2012-09-06T09:28:00+00:00","article_modified_time":"2022-08-08T09:36:10+00:00","author":"Juan Fernandez Caparros","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Juan Fernandez Caparros","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prayde.com\/empresa\/analisis-de-sensibilidad-variables\/#article","isPartOf":{"@id":"https:\/\/prayde.com\/empresa\/analisis-de-sensibilidad-variables\/"},"author":{"name":"Juan Fernandez Caparros","@id":"https:\/\/prayde.com\/empresa\/#\/schema\/person\/ef6008d6bbfeae510b73653264512798"},"headline":"An\u00e1lisis de Sensibilidad. Variables Estrat\u00e9gicas frente a Alternativas de Viabilidad","datePublished":"2012-09-06T09:28:00+00:00","dateModified":"2022-08-08T09:36:10+00:00","mainEntityOfPage":{"@id":"https:\/\/prayde.com\/empresa\/analisis-de-sensibilidad-variables\/"},"wordCount":470,"commentCount":0,"publisher":{"@id":"https:\/\/prayde.com\/empresa\/#organization"},"keywords":["analisis","viabilidad","vivienda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prayde.com\/empresa\/analisis-de-sensibilidad-variables\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prayde.com\/empresa\/analisis-de-sensibilidad-variables\/","url":"https:\/\/prayde.com\/empresa\/analisis-de-sensibilidad-variables\/","name":"An\u00e1lisis de Sensibilidad. Variables Estrat\u00e9gicas frente a Alternativas de Viabilidad - Gestinmo","isPartOf":{"@id":"https:\/\/prayde.com\/empresa\/#website"},"datePublished":"2012-09-06T09:28:00+00:00","dateModified":"2022-08-08T09:36:10+00:00","breadcrumb":{"@id":"https:\/\/prayde.com\/empresa\/analisis-de-sensibilidad-variables\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prayde.com\/empresa\/analisis-de-sensibilidad-variables\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/prayde.com\/empresa\/analisis-de-sensibilidad-variables\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/prayde.com\/empresa\/"},{"@type":"ListItem","position":2,"name":"An\u00e1lisis de Sensibilidad. Variables Estrat\u00e9gicas frente a Alternativas de Viabilidad"}]},{"@type":"WebSite","@id":"https:\/\/prayde.com\/empresa\/#website","url":"https:\/\/prayde.com\/empresa\/","name":"Gestinmo","description":"Analizar la Rentabilidad y Riesgos de una Promocion Inmobiliaria","publisher":{"@id":"https:\/\/prayde.com\/empresa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prayde.com\/empresa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/prayde.com\/empresa\/#organization","name":"Gestinmo","url":"https:\/\/prayde.com\/empresa\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/prayde.com\/empresa\/#\/schema\/logo\/image\/","url":"https:\/\/prayde.com\/empresa\/wp-content\/uploads\/2018\/12\/cropped-cropped-Prayde-Pe.jpg","contentUrl":"https:\/\/prayde.com\/empresa\/wp-content\/uploads\/2018\/12\/cropped-cropped-Prayde-Pe.jpg","width":512,"height":512,"caption":"Gestinmo"},"image":{"@id":"https:\/\/prayde.com\/empresa\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/prayde.com\/empresa\/#\/schema\/person\/ef6008d6bbfeae510b73653264512798","name":"Juan Fernandez Caparros","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"Juan Fernandez Caparros"},"url":"https:\/\/prayde.com\/empresa\/author\/06357885663078594681\/"}]}},"_links":{"self":[{"href":"https:\/\/prayde.com\/empresa\/wp-json\/wp\/v2\/posts\/1834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prayde.com\/empresa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prayde.com\/empresa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prayde.com\/empresa\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/prayde.com\/empresa\/wp-json\/wp\/v2\/comments?post=1834"}],"version-history":[{"count":0,"href":"https:\/\/prayde.com\/empresa\/wp-json\/wp\/v2\/posts\/1834\/revisions"}],"wp:attachment":[{"href":"https:\/\/prayde.com\/empresa\/wp-json\/wp\/v2\/media?parent=1834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prayde.com\/empresa\/wp-json\/wp\/v2\/categories?post=1834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prayde.com\/empresa\/wp-json\/wp\/v2\/tags?post=1834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}